{"id":302,"date":"2017-02-23T12:44:33","date_gmt":"2017-02-23T15:44:33","guid":{"rendered":"http:\/\/caetenews.com.br\/blog2\/medicinanatural\/?p=302"},"modified":"2017-02-23T12:44:33","modified_gmt":"2017-02-23T15:44:33","slug":"medicamentos-naturais-na-doenca-de-parkinson","status":"publish","type":"post","link":"https:\/\/caetenews.com.br\/mednatural\/medicamentos-naturais-na-doenca-de-parkinson\/","title":{"rendered":"Medicamentos Naturais na Doen\u00e7a de Parkinson"},"content":{"rendered":"<p>Descrita pela primeira vez por James Parkinson em 1917, a doen\u00e7a de Parkinson \u00e9 caracterizada por uma desordem progressiva do movimento muscular devido \u00e0 disfun\u00e7\u00e3o dos neur\u00f4nios produtores de uma subst\u00e2ncia conhecida como dopamina.<br \/>\nA regi\u00e3o cerebral mais acometida \u00e9 a subst\u00e2ncia nigra, nos g\u00e2nglios da base. N\u00e3o somente os neur\u00f4nios produtores de dopamina est\u00e3o envolvidos, mas outras estruturas produtoras de serotonina, noradrenalina e acetilcolina est\u00e3o envolvidos na g\u00eanese da doen\u00e7a. A Doen\u00e7a de Parkinson n\u00e3o tem causa definida, mas outras formas de parkinsonismo, como os casos gen\u00e9ticos ou secund\u00e1rios a outras doen\u00e7as ou exposi\u00e7\u00e3o a subst\u00e2ncias, e mesmo os chamados parkinsonismos at\u00edpicos podem existir, acometendo pessoas de todas as idades e sexos, mas com preval\u00eancia maior em pessoas acima de 60 anos de idade. Uma das poss\u00edveis causas da Doen\u00e7a de Parkinson, \u00e9 a ingest\u00e3o de compostos organofosforados e radioativos, presentes nos pesticidas, sendo passados aos humanos atrav\u00e9s das frutas e legumes tratados com agrot\u00f3xicos. A doen\u00e7a se pronuncia com a perda dos movimentos finos das m\u00e3os com dificuldade em escrever e tremores do membro superior ( geralmente s\u00f3 um bra\u00e7o ), al\u00e9m da altera\u00e7\u00e3o da coordena\u00e7\u00e3o da marcha e perda dos movimentos da m\u00edmica facial, temos tamb\u00e9m altera\u00e7\u00e3o da percep\u00e7\u00e3o. O paciente portador de Parkinson, n\u00e3o apresenta express\u00e3o facial e lembra um &#8220;boneco de cera&#8221;. Muitas pesquisas t\u00eam sido desenvolvidas para combater este processo degenerativo, aparecendo na medicina natural alguns fitoter\u00e1picos que se apresentam como promissores medicamentos. Atualmente temos uma planta vindo da \u00cdndia, chamada Mucuma Procubens que tem a capacidade de promover a restaura\u00e7\u00e3o da produ\u00e7\u00e3o dos neurotransmissores e portanto devolver ao cliente os movimentos harmoniosos. Outra planta que tem se mostrado eficaz \u00e9 a erva mate. Sim, a nossa erva mate que usamos para fazer o ch\u00e1 e que \u00e9 muito utilizado no sul do Brasil, como o ch\u00e1 do chimarr\u00e3o. Esse efeito acaba de ser constatado por cientistas da Universidade do Extremo Sul de Santa Catarina. Depois de testar o extrato da planta em ratos induzidos \u00e0 doen\u00e7a, eles observaram que algumas de suas subst\u00e2ncias mostraram-se capazes de proteg\u00ea-los. Em outra investiga\u00e7\u00e3o os animais receberam o fitoter\u00e1pico com a medica\u00e7\u00e3o tradicional e os resultados foram ainda mais significativos. Parte das cobaias chegou a recuperar completamente os movimentos. O estudo ainda \u00e9 preliminar, mas j\u00e1 provou que a erva-mate pode ser utilizada na preven\u00e7\u00e3o desse mal degenerativo e tamb\u00e9m como coadjuvante no tratamento. Outros m\u00e9todos naturais utilizados no tratamento e preven\u00e7\u00e3o da doen\u00e7a de Parkinson s\u00e3o a acupuntura, a homeopatia e a antroposofia, que juntamente com as ervas medicinais constituem terap\u00eauticas de eficaz a\u00e7\u00e3o. Uma quest\u00e3o que gostar\u00edamos de chamar a aten\u00e7\u00e3o \u00e9 para os inseticidas, muitos deles liberados pela Anvisa, que s\u00e3o os agrot\u00f3xicos. Utilizados para proteger as lavouras das pragas, a utiliza\u00e7\u00e3o sem precedentes impregna os alimentos de metais pesados e estes, cuja a\u00e7\u00e3o \u00e9 paralisar o sistema nervoso dos insetos, matando-os, tamb\u00e9m lesam o sistema nervoso de quem consome. Fica aqui um conselho para todos: Os alimentos que cont\u00e9m n\u00edveis exageros de agrot\u00f3xicos, s\u00e3o venenos que degeneram as c\u00e9lulas nervosas e ao inv\u00e9s de nutrir, contribuem para a forma\u00e7\u00e3o de doen\u00e7as degenerativas cerebrais. Portanto uma vida saud\u00e1vel passa por uma criteriosa forma de avaliar a alimenta\u00e7\u00e3o.<br \/>\nAt\u00e9 a pr\u00f3xima<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"slide-text-bg2\">\n<h3>Descrita pela primeira vez por James Parkinson em 1917, a doen\u00e7a de Parkinson \u00e9 caracterizada por uma desordem progressiva do<\/h3>\n<\/div>\n<div class=\"flex-btn-div\"><a href=\"https:\/\/caetenews.com.br\/mednatural\/medicamentos-naturais-na-doenca-de-parkinson\/\" class=\"btn1 flex-btn\">Ler mais<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-302","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/posts\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":1,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":303,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/posts\/302\/revisions\/303"}],"wp:attachment":[{"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caetenews.com.br\/mednatural\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}